{"id":2052,"date":"2023-01-03T17:02:36","date_gmt":"2023-01-03T15:02:36","guid":{"rendered":"https:\/\/www.labware.it\/?post_type=news&#038;p=2052"},"modified":"2023-01-03T17:09:54","modified_gmt":"2023-01-03T15:09:54","slug":"labware-torna-al-sigep","status":"publish","type":"news","link":"https:\/\/www.labware.it\/en\/news\/labware-torna-al-sigep\/","title":{"rendered":"Labware returns to Sigep, see you in Rimini!"},"content":{"rendered":"<p><strong>We look forward to seeing you at Sigep! You will find us in Hall A3, booth 189.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>We are pleased to announce our presence at the upcoming<strong> SIGEP 2023 scheduled for January 21-25 in Rimini.<\/strong><br \/>\nAfter a few years' absence, Labware returns to Sigep to present the latest innovations developed for the world of catering and hospitality.<\/p>\n<p>The past year has been full of changes with many products and services released. But the news is not over yet, the occasion of Sigep will be perfect to meet, experience and try the #LabwarExperience.<\/p>\n<p>At our booth there will be an opportunity to have an interactive experience with our products and services because we are proud to show you our increasingly comprehensive and fully integrated solution.<\/p>\n<p>&nbsp;<\/p>\n<p>It will be a pleasure to host you in our space, listen to your experiences, understand your new needs together, and explain in detail the new cloud products and services that we will present right at Sigep.<\/p>\n<p>&nbsp;<\/p>\n<p>We do not want to and cannot tell you more! <strong>We look forward to seeing you in Rimini from January 21 to 25, Hall A3 booth 189!<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em>The Labware Team<\/em><\/p>","protected":false},"featured_media":2076,"template":"","class_list":["post-2052","news","type-news","status-publish","has-post-thumbnail","hentry","articles-events"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Vi aspettiamo al Sigep! Ci troverete al padiglione A3, stand 189. Siamo lieti di annunciare la nostra presenza al prossimo SIGEP 2023 in programma dal 21 al 25 Gennaio a Rimini. Dopo qualche anno di assenza, Labware torna al Sigep per presentare le ultime novit\u00e0 sviluppate per il mondo della ristorazione e dell\u2019ospitalit\u00e0. L\u2019ultimo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.labware.it\/en\/news\/labware-torna-al-sigep\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Labware - Hospitality and Retail\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Labware torna al Sigep, ci vediamo a Rimini! - Labware\" \/>\n\t\t<meta property=\"og:description\" content=\"Vi aspettiamo al Sigep! Ci troverete al padiglione A3, stand 189. Siamo lieti di annunciare la nostra presenza al prossimo SIGEP 2023 in programma dal 21 al 25 Gennaio a Rimini. Dopo qualche anno di assenza, Labware torna al Sigep per presentare le ultime novit\u00e0 sviluppate per il mondo della ristorazione e dell\u2019ospitalit\u00e0. L\u2019ultimo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.labware.it\/en\/news\/labware-torna-al-sigep\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.labware.it\/content\/uploads\/2022\/07\/logo_labware.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.labware.it\/content\/uploads\/2022\/07\/logo_labware.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-01-03T15:02:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-01-03T15:09:54+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Labware torna al Sigep, ci vediamo a Rimini! - Labware\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Vi aspettiamo al Sigep! Ci troverete al padiglione A3, stand 189. Siamo lieti di annunciare la nostra presenza al prossimo SIGEP 2023 in programma dal 21 al 25 Gennaio a Rimini. Dopo qualche anno di assenza, Labware torna al Sigep per presentare le ultime novit\u00e0 sviluppate per il mondo della ristorazione e dell\u2019ospitalit\u00e0. L\u2019ultimo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.labware.it\/content\/uploads\/2022\/07\/logo_labware.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.labware.it\\\/en\\\/news\\\/labware-torna-al-sigep\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.labware.it\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.labware.it\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.labware.it\\\/en\\\/news\\\/#listItem\",\"name\":\"News\\\/Events\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.labware.it\\\/en\\\/news\\\/#listItem\",\"position\":2,\"name\":\"News\\\/Events\",\"item\":\"https:\\\/\\\/www.labware.it\\\/en\\\/news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.labware.it\\\/en\\\/articles\\\/events\\\/#listItem\",\"name\":\"Events\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.labware.it\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.labware.it\\\/en\\\/articles\\\/events\\\/#listItem\",\"position\":3,\"name\":\"Events\",\"item\":\"https:\\\/\\\/www.labware.it\\\/en\\\/articles\\\/events\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.labware.it\\\/en\\\/news\\\/labware-torna-al-sigep\\\/#listItem\",\"name\":\"Labware torna al Sigep, ci vediamo a Rimini!\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.labware.it\\\/en\\\/news\\\/#listItem\",\"name\":\"News\\\/Events\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.labware.it\\\/en\\\/news\\\/labware-torna-al-sigep\\\/#listItem\",\"position\":4,\"name\":\"Labware torna al Sigep, ci vediamo a Rimini!\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.labware.it\\\/en\\\/articles\\\/events\\\/#listItem\",\"name\":\"Events\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.labware.it\\\/en\\\/#organization\",\"name\":\"Labware\",\"description\":\"Hospitality and Retail\",\"url\":\"https:\\\/\\\/www.labware.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.labware.it\\\/content\\\/uploads\\\/2022\\\/07\\\/logo_labware.svg\",\"@id\":\"https:\\\/\\\/www.labware.it\\\/en\\\/news\\\/labware-torna-al-sigep\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.labware.it\\\/en\\\/news\\\/labware-torna-al-sigep\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.labware.it\\\/en\\\/news\\\/labware-torna-al-sigep\\\/#webpage\",\"url\":\"https:\\\/\\\/www.labware.it\\\/en\\\/news\\\/labware-torna-al-sigep\\\/\",\"name\":\"Labware torna al Sigep, ci vediamo a Rimini! - Labware\",\"description\":\"Vi aspettiamo al Sigep! Ci troverete al padiglione A3, stand 189. Siamo lieti di annunciare la nostra presenza al prossimo SIGEP 2023 in programma dal 21 al 25 Gennaio a Rimini. Dopo qualche anno di assenza, Labware torna al Sigep per presentare le ultime novit\\u00e0 sviluppate per il mondo della ristorazione e dell\\u2019ospitalit\\u00e0. L\\u2019ultimo\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.labware.it\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.labware.it\\\/en\\\/news\\\/labware-torna-al-sigep\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.labware.it\\\/content\\\/uploads\\\/2023\\\/01\\\/news-sito.png\",\"@id\":\"https:\\\/\\\/www.labware.it\\\/en\\\/news\\\/labware-torna-al-sigep\\\/#mainImage\",\"width\":1500,\"height\":941},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.labware.it\\\/en\\\/news\\\/labware-torna-al-sigep\\\/#mainImage\"},\"datePublished\":\"2023-01-03T17:02:36+02:00\",\"dateModified\":\"2023-01-03T17:09:54+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.labware.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.labware.it\\\/en\\\/\",\"name\":\"Labware\",\"description\":\"Hospitality and Retail\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.labware.it\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Labware torna al Sigep, ci vediamo a Rimini! - Labware","description":"Vi aspettiamo al Sigep! Ci troverete al padiglione A3, stand 189. Siamo lieti di annunciare la nostra presenza al prossimo SIGEP 2023 in programma dal 21 al 25 Gennaio a Rimini. Dopo qualche anno di assenza, Labware torna al Sigep per presentare le ultime novit\u00e0 sviluppate per il mondo della ristorazione e dell\u2019ospitalit\u00e0. L\u2019ultimo","canonical_url":"https:\/\/www.labware.it\/en\/news\/labware-torna-al-sigep\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.labware.it\/en\/news\/labware-torna-al-sigep\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.labware.it\/en#listItem","position":1,"name":"Home","item":"https:\/\/www.labware.it\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/www.labware.it\/en\/news\/#listItem","name":"News\/Events"}},{"@type":"ListItem","@id":"https:\/\/www.labware.it\/en\/news\/#listItem","position":2,"name":"News\/Events","item":"https:\/\/www.labware.it\/en\/news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.labware.it\/en\/articles\/events\/#listItem","name":"Events"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.labware.it\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.labware.it\/en\/articles\/events\/#listItem","position":3,"name":"Events","item":"https:\/\/www.labware.it\/en\/articles\/events\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.labware.it\/en\/news\/labware-torna-al-sigep\/#listItem","name":"Labware torna al Sigep, ci vediamo a Rimini!"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.labware.it\/en\/news\/#listItem","name":"News\/Events"}},{"@type":"ListItem","@id":"https:\/\/www.labware.it\/en\/news\/labware-torna-al-sigep\/#listItem","position":4,"name":"Labware torna al Sigep, ci vediamo a Rimini!","previousItem":{"@type":"ListItem","@id":"https:\/\/www.labware.it\/en\/articles\/events\/#listItem","name":"Events"}}]},{"@type":"Organization","@id":"https:\/\/www.labware.it\/en\/#organization","name":"Labware","description":"Hospitality and Retail","url":"https:\/\/www.labware.it\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/www.labware.it\/content\/uploads\/2022\/07\/logo_labware.svg","@id":"https:\/\/www.labware.it\/en\/news\/labware-torna-al-sigep\/#organizationLogo"},"image":{"@id":"https:\/\/www.labware.it\/en\/news\/labware-torna-al-sigep\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/www.labware.it\/en\/news\/labware-torna-al-sigep\/#webpage","url":"https:\/\/www.labware.it\/en\/news\/labware-torna-al-sigep\/","name":"Labware torna al Sigep, ci vediamo a Rimini! - Labware","description":"Vi aspettiamo al Sigep! Ci troverete al padiglione A3, stand 189. Siamo lieti di annunciare la nostra presenza al prossimo SIGEP 2023 in programma dal 21 al 25 Gennaio a Rimini. Dopo qualche anno di assenza, Labware torna al Sigep per presentare le ultime novit\u00e0 sviluppate per il mondo della ristorazione e dell\u2019ospitalit\u00e0. L\u2019ultimo","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.labware.it\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.labware.it\/en\/news\/labware-torna-al-sigep\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.labware.it\/content\/uploads\/2023\/01\/news-sito.png","@id":"https:\/\/www.labware.it\/en\/news\/labware-torna-al-sigep\/#mainImage","width":1500,"height":941},"primaryImageOfPage":{"@id":"https:\/\/www.labware.it\/en\/news\/labware-torna-al-sigep\/#mainImage"},"datePublished":"2023-01-03T17:02:36+02:00","dateModified":"2023-01-03T17:09:54+02:00"},{"@type":"WebSite","@id":"https:\/\/www.labware.it\/en\/#website","url":"https:\/\/www.labware.it\/en\/","name":"Labware","description":"Hospitality and Retail","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.labware.it\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Labware - Hospitality and Retail","og:type":"article","og:title":"Labware torna al Sigep, ci vediamo a Rimini! - Labware","og:description":"Vi aspettiamo al Sigep! Ci troverete al padiglione A3, stand 189. Siamo lieti di annunciare la nostra presenza al prossimo SIGEP 2023 in programma dal 21 al 25 Gennaio a Rimini. Dopo qualche anno di assenza, Labware torna al Sigep per presentare le ultime novit\u00e0 sviluppate per il mondo della ristorazione e dell\u2019ospitalit\u00e0. L\u2019ultimo","og:url":"https:\/\/www.labware.it\/en\/news\/labware-torna-al-sigep\/","og:image":"https:\/\/www.labware.it\/content\/uploads\/2022\/07\/logo_labware.svg","og:image:secure_url":"https:\/\/www.labware.it\/content\/uploads\/2022\/07\/logo_labware.svg","article:published_time":"2023-01-03T15:02:36+00:00","article:modified_time":"2023-01-03T15:09:54+00:00","twitter:card":"summary_large_image","twitter:title":"Labware torna al Sigep, ci vediamo a Rimini! - Labware","twitter:description":"Vi aspettiamo al Sigep! Ci troverete al padiglione A3, stand 189. Siamo lieti di annunciare la nostra presenza al prossimo SIGEP 2023 in programma dal 21 al 25 Gennaio a Rimini. Dopo qualche anno di assenza, Labware torna al Sigep per presentare le ultime novit\u00e0 sviluppate per il mondo della ristorazione e dell\u2019ospitalit\u00e0. L\u2019ultimo","twitter:image":"https:\/\/www.labware.it\/content\/uploads\/2022\/07\/logo_labware.svg"},"aioseo_meta_data":{"post_id":"2052","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-12-18 18:47:08","updated":"2025-06-04 12:55:41","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.labware.it\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.labware.it\/en\/news\/\" title=\"News\/Events\">News\/Events<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.labware.it\/en\/articles\/events\/\" title=\"Events\">Events<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLabware torna al Sigep, ci vediamo a Rimini!\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.labware.it\/en"},{"label":"News\/Events","link":"https:\/\/www.labware.it\/en\/news\/"},{"label":"Events","link":"https:\/\/www.labware.it\/en\/articles\/events\/"},{"label":"Labware torna al Sigep, ci vediamo a Rimini!","link":"https:\/\/www.labware.it\/en\/news\/labware-torna-al-sigep\/"}],"_links":{"self":[{"href":"https:\/\/www.labware.it\/en\/wp-json\/wp\/v2\/news\/2052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labware.it\/en\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.labware.it\/en\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.labware.it\/en\/wp-json\/wp\/v2\/media\/2076"}],"wp:attachment":[{"href":"https:\/\/www.labware.it\/en\/wp-json\/wp\/v2\/media?parent=2052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}